{"id":5603,"date":"2025-03-18T13:25:03","date_gmt":"2025-03-18T12:25:03","guid":{"rendered":"https:\/\/catenificiorigamonti.com\/prodotto\/calibrated-short-link-chain-in-reels\/"},"modified":"2025-03-21T12:21:03","modified_gmt":"2025-03-21T11:21:03","slug":"calibrated-short-link-chain-in-reels","status":"publish","type":"product","link":"https:\/\/catenificiorigamonti.com\/en\/prodotto\/calibrated-short-link-chain-in-reels\/","title":{"rendered":"Calibrated short link chain in reels"},"content":{"rendered":"<table border=1>\n<thead>\n<tr>\n<th>W (mm)<\/p>\n<th>Cod. Art. \/ Art. Code (Bobina EZ)<\/p>\n<th>Bobina \/ Mt (Mts \/ Reel EZ)<\/p>\n<th>Cod. Art. \/ Art. Code (Bobina EF)<\/p>\n<th>Bobina \/ Mt (Mts \/ Reel EF)<\/p>\n<th>Cod. Art. \/ Art. Code (Bobina EB)<\/p>\n<th>Bobina \/ Mt (Mts \/ Reel EB)<\/p>\n<tbody>\n<tr>\n<td>3<\/p>\n<td>C03030EZ<\/p>\n<td>50<\/p>\n<td>C03030EF<\/p>\n<td>50<\/p>\n<td>C03030EB<\/p>\n<td>50<\/p>\n<tr>\n<td>4<\/p>\n<td>C03040EZ<\/p>\n<td>50<\/p>\n<td>C03040EF<\/p>\n<td>50<\/p>\n<td>C03040EB<\/p>\n<td>50<\/p>\n<tr>\n<td>5<\/p>\n<td>C03050EZ<\/p>\n<td>40<\/p>\n<td>C03050EF<\/p>\n<td>40<\/p>\n<td>C03050EB<\/p>\n<td>40<\/p>\n<tr>\n<td>6<\/p>\n<td>C03060EZ<\/p>\n<td>30<\/p>\n<td>C03060EF<\/p>\n<td>30<\/p>\n<td>C03060EB<\/p>\n<td>30<\/p>\n<tr>\n<td>7<\/p>\n<td>C03070EZ\/25<\/p>\n<td>25<\/p>\n<td>C03070EF<\/p>\n<td>25<\/p>\n<td>&#8211;<\/p>\n<td>&#8211;<\/p>\n<tr>\n<td>8<\/p>\n<td>C03080EZ<\/p>\n<td>22<\/p>\n<td>C03080EF<\/p>\n<td>22<\/p>\n<td>C03080EB<\/p>\n<td>22<\/p>\n<tr>\n<td>9<\/p>\n<td>C03090EZ<\/p>\n<td>15<\/p>\n<td>C03090EF<\/p>\n<td>15<\/p>\n<td>&#8211;<\/p>\n<td>&#8211;<\/p>\n<tr>\n<td>10<\/p>\n<td>C03100EZ<\/p>\n<td>10<\/p>\n<td>C03100EF<\/p>\n<td>10<\/p>\n<td>C03100EB<\/p>\n<td>10<\/p>\n<tr>\n<td>10<\/p>\n<td>C03100EZ\/30<\/p>\n<td>10<\/p>\n<td>C03100EF\/30<\/p>\n<td>10<\/p>\n<td>C03100EB\/30<\/p>\n<td>10<\/p>\n<tr>\n<td>11<\/p>\n<td>C03110EZ<\/p>\n<td>10<\/p>\n<td>C03110EF<\/p>\n<td>10<\/p>\n<td>&#8211;<\/p>\n<td>&#8211;<\/p>\n<tr>\n<td>12<\/p>\n<td>C03120EZ<\/p>\n<td>10<\/p>\n<td>C03120EF<\/p>\n<td>10<\/p>\n<td>C03120EB<\/p>\n<td>10<\/table>\n","protected":false},"excerpt":{"rendered":"<p>W (mm) Cod. Art. \/ Art. Code (Bobina EZ) Bobina \/ Mt (Mts \/ Reel EZ) Cod. Art. \/ Art. Code (Bobina EF) Bobina \/ Mt (Mts \/ Reel EF) Cod. Art. \/ Art. Code (Bobina EB) Bobina \/ Mt (Mts \/ Reel EB) 3 C03030EZ 50 C03030EF 50 C03030EB 50 4 C03040EZ 50 C03040EF [&hellip;]<\/p>\n","protected":false},"featured_media":4878,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[419,423,835,417],"product_tag":[],"class_list":{"0":"post-5603","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-diy","7":"product_cat-marine","8":"product_cat-stainless-steel","9":"product_cat-urban-furnishing","11":"first","12":"instock","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/product\/5603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/comments?post=5603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/media\/4878"}],"wp:attachment":[{"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/media?parent=5603"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/product_brand?post=5603"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/product_cat?post=5603"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/catenificiorigamonti.com\/en\/wp-json\/wp\/v2\/product_tag?post=5603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}